{"id":97,"count":36,"description":"","link":"https:\/\/allwintheme.com\/es\/etiqueta\/cartera\/","name":"Cartera","slug":"cartera","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Portfolio Archives -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/allwintheme.com\/es\/etiqueta\/cartera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portfolio Archives\" \/>\n<meta property=\"og:url\" content=\"http:\/\/allwintheme.com\/es\/etiqueta\/cartera\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/allwintheme.com\\\/tag\\\/portfolio\\\/\",\"url\":\"http:\\\/\\\/allwintheme.com\\\/tag\\\/portfolio\\\/\",\"name\":\"Portfolio Archives -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/allwintheme.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/allwintheme.com\\\/tag\\\/portfolio\\\/#breadcrumb\"},\"inLanguage\":\"es-CL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/allwintheme.com\\\/tag\\\/portfolio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/allwintheme.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/allwintheme.com\\\/#website\",\"url\":\"https:\\\/\\\/allwintheme.com\\\/\",\"name\":\"Allwintheme\",\"description\":\"Download 100% GPL-licensed WordPress themes, plugins, and PHP scripts. Free, safe, regularly updated. Perfect for any niche.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/allwintheme.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CL\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Portfolio Archives -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/allwintheme.com\/es\/etiqueta\/cartera\/","og_locale":"es_ES","og_type":"article","og_title":"Portfolio Archives","og_url":"http:\/\/allwintheme.com\/es\/etiqueta\/cartera\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/allwintheme.com\/tag\/portfolio\/","url":"http:\/\/allwintheme.com\/tag\/portfolio\/","name":"Archivos del portafolio -","isPartOf":{"@id":"https:\/\/allwintheme.com\/#website"},"breadcrumb":{"@id":"http:\/\/allwintheme.com\/tag\/portfolio\/#breadcrumb"},"inLanguage":"es-CL"},{"@type":"BreadcrumbList","@id":"http:\/\/allwintheme.com\/tag\/portfolio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/allwintheme.com\/"},{"@type":"ListItem","position":2,"name":"Portfolio"}]},{"@type":"WebSite","@id":"https:\/\/allwintheme.com\/#website","url":"https:\/\/allwintheme.com\/","name":"Allwintheme","description":"Descargue 100% temas, plugins y scripts PHP para WordPress con licencia GPL. Gratis, seguros y actualizados con regularidad. Perfecto para cualquier nicho.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/allwintheme.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CL"}]}},"_links":{"self":[{"href":"https:\/\/allwintheme.com\/es\/wp-json\/wp\/v2\/tags\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allwintheme.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/allwintheme.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/allwintheme.com\/es\/wp-json\/wp\/v2\/posts?tags=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}